{"id":3738,"date":"2013-06-01T00:00:00","date_gmt":"2013-06-01T00:00:00","guid":{"rendered":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/"},"modified":"2013-06-01T00:00:00","modified_gmt":"2013-06-01T00:00:00","slug":"journee-de-lancement-des-activites-au-club","status":"publish","type":"post","link":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/","title":{"rendered":"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB"},"content":{"rendered":"<p>Vous \u00eates invit\u00e9s \u00e0 venir participer \u00e0 la Journ\u00e9e de lancement des activit\u00e9s au Club nautique samedi le 1er juin d\u00e8s 10 h 00.<br \/>\n\u00c0 cette occasion, nos concessionnaires partenaires (Cloutier Sports, Dion Moto, Performance Voyer, Pomerleau Les Bateaux et Adr\u00e9naline Sports) seront sur place pour vous faire d\u00e9couvrir et m\u00eame essayer leurs bateaux, pontons, VTT, C\u00f4te-\u00e0-c\u00f4te et Spyder.<br \/>\nDe plus, d\u2019autres activit\u00e9s rassembleuses ont \u00e9t\u00e9 organis\u00e9es pour vous :<br \/>\n\u2022 10 h 30 \u00e0 14 h 30 Clowns et animations pour enfants<br \/>\n\u2022 11 h 00 Verre de l&rsquo;amiti\u00e9 offert par l&rsquo;APLSI<br \/>\n\u2022 12 h 00 Party de hot-dogs<br \/>\n\u2022 17 h 00 Cl\u00f4ture des activit\u00e9s<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vous \u00eates invit\u00e9s \u00e0 venir participer \u00e0 la Journ\u00e9e de lancement des activit\u00e9s au Club nautique samedi le 1er juin <a href=\"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":7033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[16],"tags":[74],"class_list":["post-3738","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-activites","tag-74"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB - Association des propri\u00e9taires du Lac Sept-\u00celes<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB - Association des propri\u00e9taires du Lac Sept-\u00celes\" \/>\n<meta property=\"og:description\" content=\"Vous \u00eates invit\u00e9s \u00e0 venir participer \u00e0 la Journ\u00e9e de lancement des activit\u00e9s au Club nautique samedi le 1er juin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des propri\u00e9taires du Lac Sept-\u00celes\" \/>\n<meta property=\"article:published_time\" content=\"2013-06-01T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Communication Gmail APLSI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication Gmail APLSI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/\"},\"author\":{\"name\":\"Communication Gmail APLSI\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\"},\"headline\":\"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB\",\"datePublished\":\"2013-06-01T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/\"},\"wordCount\":112,\"image\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"keywords\":[\"2013\"],\"articleSection\":[\"Activit\u00e9s\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/\",\"name\":\"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB - Association des propri\u00e9taires du Lac Sept-\u00celes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"datePublished\":\"2013-06-01T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/journee-de-lancement-des-activites-au-club\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#website\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/\",\"name\":\"Association des propri\u00e9taires du Lac Sept-\u00celes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\",\"name\":\"Communication Gmail APLSI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"contentUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"caption\":\"Communication Gmail APLSI\"},\"sameAs\":[\"https:\\\/\\\/aplsi.com\\\/site-de-test\"],\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/author\\\/adminaplsi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB - Association des propri\u00e9taires du Lac Sept-\u00celes","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB - Association des propri\u00e9taires du Lac Sept-\u00celes","og_description":"Vous \u00eates invit\u00e9s \u00e0 venir participer \u00e0 la Journ\u00e9e de lancement des activit\u00e9s au Club nautique samedi le 1er juin [&hellip;]","og_url":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/","og_site_name":"Association des propri\u00e9taires du Lac Sept-\u00celes","article_published_time":"2013-06-01T00:00:00+00:00","author":"Communication Gmail APLSI","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Communication Gmail APLSI","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#article","isPartOf":{"@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/"},"author":{"name":"Communication Gmail APLSI","@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b"},"headline":"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB","datePublished":"2013-06-01T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/"},"wordCount":112,"image":{"@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#primaryimage"},"thumbnailUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","keywords":["2013"],"articleSection":["Activit\u00e9s"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/","url":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/","name":"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB - Association des propri\u00e9taires du Lac Sept-\u00celes","isPartOf":{"@id":"https:\/\/aplsi.com\/site-de-test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#primaryimage"},"image":{"@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#primaryimage"},"thumbnailUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","datePublished":"2013-06-01T00:00:00+00:00","author":{"@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b"},"breadcrumb":{"@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#primaryimage","url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","contentUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/aplsi.com\/site-de-test\/journee-de-lancement-des-activites-au-club\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aplsi.com\/site-de-test\/"},{"@type":"ListItem","position":2,"name":"JOURN\u00c9E DE LANCEMENT DES ACTIVIT\u00c9S AU CLUB"}]},{"@type":"WebSite","@id":"https:\/\/aplsi.com\/site-de-test\/#website","url":"https:\/\/aplsi.com\/site-de-test\/","name":"Association des propri\u00e9taires du Lac Sept-\u00celes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aplsi.com\/site-de-test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b","name":"Communication Gmail APLSI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","contentUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","caption":"Communication Gmail APLSI"},"sameAs":["https:\/\/aplsi.com\/site-de-test"],"url":"https:\/\/aplsi.com\/site-de-test\/author\/adminaplsi\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 04:32:24","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/3738","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/comments?post=3738"}],"version-history":[{"count":0,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/3738\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/media\/7033"}],"wp:attachment":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/media?parent=3738"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/categories?post=3738"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/tags?post=3738"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}