{"id":4464,"date":"2016-06-13T00:00:00","date_gmt":"2016-06-13T00:00:00","guid":{"rendered":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/"},"modified":"2016-06-13T00:00:00","modified_gmt":"2016-06-13T00:00:00","slug":"une-humoriste-au-club-nautique","status":"publish","type":"post","link":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/","title":{"rendered":"UNE HUMORISTE AU CLUB NAUTIQUE"},"content":{"rendered":"<p><strong>Marie-\u00c9lise Joosten<\/strong> viendra pr\u00e9senter son spectacle d\u2019humour intitul\u00e9 <strong>SANS D\u00c9TOUR<\/strong> au Club nautique les  mercredi 29 juin, jeudi 30 juin  et mercredi 6 juillet.<br \/>\nDevant le succ\u00e8s rencontr\u00e9, de nouvelles dates s&rsquo;ajoutent au programme: <strong>MERCREDI ET JEUDI LES 20 ET 21 JUILLET.<\/strong><br \/>\nLes billets sont en vente chez Uniprix Picard et Simard \u00e0 Saint-Raymond (418 337-2238).<br \/>\nOriginaire de Saint-Raymond, Marie-\u00c9lise Joosten prend de plus en plus sa place dans le monde de l\u2019humour au Qu\u00e9bec<br \/>\nPLAISIR ASSUR\u00c9!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Marie-\u00c9lise Joosten viendra pr\u00e9senter son spectacle d\u2019humour intitul\u00e9 SANS D\u00c9TOUR au Club nautique les mercredi 29 juin, jeudi 30 juin <a href=\"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":7033,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[53],"tags":[43],"class_list":["post-4464","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-de-lassociation","tag-43"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>UNE HUMORISTE AU CLUB NAUTIQUE - Association des propri\u00e9taires du Lac Sept-\u00celes<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"UNE HUMORISTE AU CLUB NAUTIQUE - Association des propri\u00e9taires du Lac Sept-\u00celes\" \/>\n<meta property=\"og:description\" content=\"Marie-\u00c9lise Joosten viendra pr\u00e9senter son spectacle d\u2019humour intitul\u00e9 SANS D\u00c9TOUR au Club nautique les mercredi 29 juin, jeudi 30 juin [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des propri\u00e9taires du Lac Sept-\u00celes\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-13T00:00:00+00:00\" \/>\n<meta name=\"author\" content=\"Communication Gmail APLSI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication Gmail APLSI\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/\"},\"author\":{\"name\":\"Communication Gmail APLSI\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\"},\"headline\":\"UNE HUMORISTE AU CLUB NAUTIQUE\",\"datePublished\":\"2016-06-13T00:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/\"},\"wordCount\":84,\"image\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"keywords\":[\"2016\"],\"articleSection\":[\"Vie de l'association\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/\",\"name\":\"UNE HUMORISTE AU CLUB NAUTIQUE - Association des propri\u00e9taires du Lac Sept-\u00celes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"datePublished\":\"2016-06-13T00:00:00+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"contentUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/image-par-defaut-actualites-1.jpg\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/une-humoriste-au-club-nautique\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"UNE HUMORISTE AU CLUB NAUTIQUE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#website\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/\",\"name\":\"Association des propri\u00e9taires du Lac Sept-\u00celes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\",\"name\":\"Communication Gmail APLSI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"contentUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"caption\":\"Communication Gmail APLSI\"},\"sameAs\":[\"https:\\\/\\\/aplsi.com\\\/site-de-test\"],\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/author\\\/adminaplsi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"UNE HUMORISTE AU CLUB NAUTIQUE - Association des propri\u00e9taires du Lac Sept-\u00celes","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"UNE HUMORISTE AU CLUB NAUTIQUE - Association des propri\u00e9taires du Lac Sept-\u00celes","og_description":"Marie-\u00c9lise Joosten viendra pr\u00e9senter son spectacle d\u2019humour intitul\u00e9 SANS D\u00c9TOUR au Club nautique les mercredi 29 juin, jeudi 30 juin [&hellip;]","og_url":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/","og_site_name":"Association des propri\u00e9taires du Lac Sept-\u00celes","article_published_time":"2016-06-13T00:00:00+00:00","author":"Communication Gmail APLSI","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Communication Gmail APLSI"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#article","isPartOf":{"@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/"},"author":{"name":"Communication Gmail APLSI","@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b"},"headline":"UNE HUMORISTE AU CLUB NAUTIQUE","datePublished":"2016-06-13T00:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/"},"wordCount":84,"image":{"@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#primaryimage"},"thumbnailUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","keywords":["2016"],"articleSection":["Vie de l'association"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/","url":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/","name":"UNE HUMORISTE AU CLUB NAUTIQUE - Association des propri\u00e9taires du Lac Sept-\u00celes","isPartOf":{"@id":"https:\/\/aplsi.com\/site-de-test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#primaryimage"},"image":{"@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#primaryimage"},"thumbnailUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","datePublished":"2016-06-13T00:00:00+00:00","author":{"@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b"},"breadcrumb":{"@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#primaryimage","url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","contentUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/image-par-defaut-actualites-1.jpg","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/aplsi.com\/site-de-test\/une-humoriste-au-club-nautique\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aplsi.com\/site-de-test\/"},{"@type":"ListItem","position":2,"name":"UNE HUMORISTE AU CLUB NAUTIQUE"}]},{"@type":"WebSite","@id":"https:\/\/aplsi.com\/site-de-test\/#website","url":"https:\/\/aplsi.com\/site-de-test\/","name":"Association des propri\u00e9taires du Lac Sept-\u00celes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aplsi.com\/site-de-test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b","name":"Communication Gmail APLSI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","contentUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","caption":"Communication Gmail APLSI"},"sameAs":["https:\/\/aplsi.com\/site-de-test"],"url":"https:\/\/aplsi.com\/site-de-test\/author\/adminaplsi\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-21 23:06:01","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/4464","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/comments?post=4464"}],"version-history":[{"count":0,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/4464\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/media\/7033"}],"wp:attachment":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/media?parent=4464"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/categories?post=4464"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/tags?post=4464"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}