{"id":4551,"date":"2009-05-25T00:00:00","date_gmt":"2009-05-25T00:00:00","guid":{"rendered":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/"},"modified":"2026-05-27T08:44:14","modified_gmt":"2026-05-27T12:44:14","slug":"deces-de-yvon-paradis-1932-2009","status":"publish","type":"post","link":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/","title":{"rendered":"D\u00c9C\u00c8S DE Yvon Paradis 1932 &#8211; 2009"},"content":{"rendered":"<p>25 mai, d\u00e9c\u00e8s de M Yvon Paradis (un ancien pr\u00e9sident du club) Voir les d\u00e9tails<\/p>\n<p>Yvon Paradis 1932 &#8211; 2009 \u00abIl nous a tellement apport\u00e9 qu&rsquo;onne pourra jamais l&rsquo;oublier!\u00bb \u00c0 son domicile au Lac Sept-Iles, le 25 mai 2009, \u00e0 l&rsquo;\u00e2ge de 77 ans, est d\u00e9c\u00e9d\u00e9 monsieur Yvon Paradis, \u00e9poux de dame Denise Beaulieu.<\/p>\n<p>Un pilier de l\u2019APLSI n\u2019est plus.<\/p>\n<p>\u00c0 la veille d\u2019aller sous presse, nous apprenons le d\u00e9c\u00e8s d\u2019un pilier de notre association. En effet, M. Yvon Paradis vient de nous quitter. Il a \u00e9t\u00e9 \u00e0 la barre de l\u2019APLSI de 1979 \u00e0 1983. Comme pr\u00e9sident, il sait d\u00e9l\u00e9guer les t\u00e2ches aux bonnes personnes. Celles et ceux qui le c\u00f4toient alors constatent vite qu\u2019Yvon n\u2019est pas homme de discours, mais homme d\u2019action : qu\u2019est-ce qu\u2019on fait, quand et qui s\u2019en occupe? Il n\u2019aime pas non plus occuper l\u2019avant-sc\u00e8ne. C\u2019est dans l\u2019ombre qu\u2019il pr\u00e9f\u00e8re agir, mais avec combien d\u2019efficacit\u00e9! Il entra\u00eene m\u00eame dans son sillage son \u00e9pouse Denise qui met sur pied, en 1974, le bingo au profit de l\u2019association.<br \/>\nC\u2019est en 1978 qu\u2019Yvon acc\u00e8de au Bureau de direction. Il participe aux comit\u00e9s des loisirs et \u00e0 celui des activit\u00e9s sociales. C\u2019est sous sa gouverne qu\u2019est institu\u00e9e la journ\u00e9e dite \u00abLa grande rencontre\u00bb o\u00f9 diverses activit\u00e9s, jeux, souper, messe, disco et feu de camp sont au programme. L\u2019association profite \u00e9galement de son talent d\u2019homme d\u2019affaires pour l\u2019acquisition de denr\u00e9es et d\u2019\u00e9quipements tels des tables, des luminaires, des chaises et cela \u00e0 des prix imbattables. Il s\u2019occupe de la location de la vaisselle pour les soupers et surtout de la transporter. M\u00eame apr\u00e8s son d\u00e9part du Bureau de direction, il continue \u00e0 appuyer les responsables des soupers. Depuis 1974, L\u2019Alouette para\u00eet annuellement. Pendant quelques ann\u00e9es, Yvon se d\u00e9voue \u00e0 recruter des annonceurs dans la Ville de Qu\u00e9bec tout en s\u2019occupant de son commerce de La Table du Roy.<br \/>\nM\u00eame s\u2019il s\u2019est fait plus discret au cours des derni\u00e8res ann\u00e9es, Yvon n\u2019en \u00e9tait pas moins actif, particuli\u00e8rement en appuyant ses enfants dans leurs entreprises.<\/p>\n<p>\u00c0 Denise et aux enfants, nos sinc\u00e8res condol\u00e9ances<\/p>\n<p>Voir <a href=\"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/Alouette_1984.pdf\" target=\"_blank\" rel=\"noopener\">L\u2019Alouette 1984<\/a>, pp. 19 et 21 pour textes concernant Yvon.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>25 mai, d\u00e9c\u00e8s de M Yvon Paradis (un ancien pr\u00e9sident du club) Voir les d\u00e9tails Yvon Paradis 1932 &#8211; 2009 <a href=\"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/\"> [&hellip;]<\/a><\/p>\n","protected":false},"author":1,"featured_media":5502,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_monsterinsights_skip_tracking":false,"_monsterinsights_sitenote_active":false,"_monsterinsights_sitenote_note":"","_monsterinsights_sitenote_category":0,"footnotes":"","_members_access_role":[],"_members_access_error":""},"categories":[53],"tags":[42],"class_list":["post-4551","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vie-de-lassociation","tag-42"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>D\u00c9C\u00c8S DE Yvon Paradis 1932 - 2009 - Association des propri\u00e9taires du Lac Sept-\u00celes<\/title>\n<meta name=\"robots\" content=\"noindex, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"D\u00c9C\u00c8S DE Yvon Paradis 1932 - 2009 - Association des propri\u00e9taires du Lac Sept-\u00celes\" \/>\n<meta property=\"og:description\" content=\"25 mai, d\u00e9c\u00e8s de M Yvon Paradis (un ancien pr\u00e9sident du club) Voir les d\u00e9tails Yvon Paradis 1932 &#8211; 2009 [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/\" \/>\n<meta property=\"og:site_name\" content=\"Association des propri\u00e9taires du Lac Sept-\u00celes\" \/>\n<meta property=\"article:published_time\" content=\"2009-05-25T00:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2026-05-27T12:44:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/YvonParadis.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"333\" \/>\n\t<meta property=\"og:image:height\" content=\"433\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Communication Gmail APLSI\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Communication Gmail APLSI\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/\"},\"author\":{\"name\":\"Communication Gmail APLSI\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\"},\"headline\":\"D\u00c9C\u00c8S DE Yvon Paradis 1932 &#8211; 2009\",\"datePublished\":\"2009-05-25T00:00:00+00:00\",\"dateModified\":\"2026-05-27T12:44:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/\"},\"wordCount\":409,\"image\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/YvonParadis.jpg\",\"keywords\":[\"2017\"],\"articleSection\":[\"Vie de l'association\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/\",\"name\":\"D\u00c9C\u00c8S DE Yvon Paradis 1932 - 2009 - Association des propri\u00e9taires du Lac Sept-\u00celes\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/YvonParadis.jpg\",\"datePublished\":\"2009-05-25T00:00:00+00:00\",\"dateModified\":\"2026-05-27T12:44:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#primaryimage\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/YvonParadis.jpg\",\"contentUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/uploads\\\/YvonParadis.jpg\",\"width\":333,\"height\":433},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/deces-de-yvon-paradis-1932-2009\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"D\u00c9C\u00c8S DE Yvon Paradis 1932 &#8211; 2009\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#website\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/\",\"name\":\"Association des propri\u00e9taires du Lac Sept-\u00celes\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/#\\\/schema\\\/person\\\/87f66ca75ccc8f87a9fd8f3e64db5a4b\",\"name\":\"Communication Gmail APLSI\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"contentUrl\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/wp-content\\\/litespeed\\\/avatar\\\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580\",\"caption\":\"Communication Gmail APLSI\"},\"sameAs\":[\"https:\\\/\\\/aplsi.com\\\/site-de-test\"],\"url\":\"https:\\\/\\\/aplsi.com\\\/site-de-test\\\/author\\\/adminaplsi\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"D\u00c9C\u00c8S DE Yvon Paradis 1932 - 2009 - Association des propri\u00e9taires du Lac Sept-\u00celes","robots":{"index":"noindex","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"og_locale":"fr_FR","og_type":"article","og_title":"D\u00c9C\u00c8S DE Yvon Paradis 1932 - 2009 - Association des propri\u00e9taires du Lac Sept-\u00celes","og_description":"25 mai, d\u00e9c\u00e8s de M Yvon Paradis (un ancien pr\u00e9sident du club) Voir les d\u00e9tails Yvon Paradis 1932 &#8211; 2009 [&hellip;]","og_url":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/","og_site_name":"Association des propri\u00e9taires du Lac Sept-\u00celes","article_published_time":"2009-05-25T00:00:00+00:00","article_modified_time":"2026-05-27T12:44:14+00:00","og_image":[{"width":333,"height":433,"url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/YvonParadis.jpg","type":"image\/jpeg"}],"author":"Communication Gmail APLSI","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Communication Gmail APLSI","Dur\u00e9e de lecture estim\u00e9e":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#article","isPartOf":{"@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/"},"author":{"name":"Communication Gmail APLSI","@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b"},"headline":"D\u00c9C\u00c8S DE Yvon Paradis 1932 &#8211; 2009","datePublished":"2009-05-25T00:00:00+00:00","dateModified":"2026-05-27T12:44:14+00:00","mainEntityOfPage":{"@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/"},"wordCount":409,"image":{"@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#primaryimage"},"thumbnailUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/YvonParadis.jpg","keywords":["2017"],"articleSection":["Vie de l'association"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/","url":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/","name":"D\u00c9C\u00c8S DE Yvon Paradis 1932 - 2009 - Association des propri\u00e9taires du Lac Sept-\u00celes","isPartOf":{"@id":"https:\/\/aplsi.com\/site-de-test\/#website"},"primaryImageOfPage":{"@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#primaryimage"},"image":{"@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#primaryimage"},"thumbnailUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/YvonParadis.jpg","datePublished":"2009-05-25T00:00:00+00:00","dateModified":"2026-05-27T12:44:14+00:00","author":{"@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b"},"breadcrumb":{"@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#primaryimage","url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/YvonParadis.jpg","contentUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/uploads\/YvonParadis.jpg","width":333,"height":433},{"@type":"BreadcrumbList","@id":"https:\/\/aplsi.com\/site-de-test\/deces-de-yvon-paradis-1932-2009\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/aplsi.com\/site-de-test\/"},{"@type":"ListItem","position":2,"name":"D\u00c9C\u00c8S DE Yvon Paradis 1932 &#8211; 2009"}]},{"@type":"WebSite","@id":"https:\/\/aplsi.com\/site-de-test\/#website","url":"https:\/\/aplsi.com\/site-de-test\/","name":"Association des propri\u00e9taires du Lac Sept-\u00celes","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/aplsi.com\/site-de-test\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Person","@id":"https:\/\/aplsi.com\/site-de-test\/#\/schema\/person\/87f66ca75ccc8f87a9fd8f3e64db5a4b","name":"Communication Gmail APLSI","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","url":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","contentUrl":"https:\/\/aplsi.com\/site-de-test\/wp-content\/litespeed\/avatar\/9af21f58d5000be505bd74e6ca23e30f.jpg?ver=1783984580","caption":"Communication Gmail APLSI"},"sameAs":["https:\/\/aplsi.com\/site-de-test"],"url":"https:\/\/aplsi.com\/site-de-test\/author\/adminaplsi\/"}]}},"publishpress_future_action":{"enabled":false,"date":"2026-07-22 01:38:34","action":"change-status","newStatus":"draft","terms":[],"taxonomy":"category","extraData":[]},"publishpress_future_workflow_manual_trigger":{"enabledWorkflows":[]},"_links":{"self":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/4551","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/comments?post=4551"}],"version-history":[{"count":4,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/4551\/revisions"}],"predecessor-version":[{"id":5505,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/posts\/4551\/revisions\/5505"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/media\/5502"}],"wp:attachment":[{"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/media?parent=4551"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/categories?post=4551"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/aplsi.com\/site-de-test\/wp-json\/wp\/v2\/tags?post=4551"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}